{"id":27281,"date":"2023-07-19T11:24:12","date_gmt":"2023-07-19T09:24:12","guid":{"rendered":"https:\/\/www.skg.ch\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/"},"modified":"2024-06-18T12:55:03","modified_gmt":"2024-06-18T10:55:03","slug":"a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco","status":"publish","type":"post","link":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/","title":{"rendered":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27281\" class=\"elementor elementor-27281 elementor-27220\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1304f36 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1304f36\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad6db6b\" data-id=\"ad6db6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1bb54c elementor-widget elementor-widget-text-editor\" data-id=\"d1bb54c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Non sono solo le persone a soffrire il caldo in piena estate: anche i nostri amici a quattro zampe non lo sopportano. Se seguite alcuni semplici accorgimenti, aiuterete il vostro cane a superare bene e in salute i giorni della canicola.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf6f862 elementor-widget elementor-widget-text-editor\" data-id=\"cf6f862\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I giorni della canicola annuale iniziano il 23 luglio e durano fino al 23 agosto. Anche se il nome suggerisce il contrario, questo periodo dell&#8217;anno non ha nulla a che fare con i nostri cani, ma \u00e8 cos\u00ec chiamato per una ragione astronomica: si tratta del periodo in cui, appunto, Canicola, la stella meglio nota come Sirio, sorge e tramonta insieme al Sole, e la stella principale si trova nella costellazione del \u00abCane maggiore\u00bb. O perlomeno era cos\u00ec quando i Romani, che hanno coniato il termine, guardavano il cielo. Oggi per\u00f2, questo non \u00e8 pi\u00f9 vero. Il corso delle stelle e della terra si \u00e8 infatti spostato nel tempo rispetto all&#8217;epoca dell&#8217;Impero Romano (pi\u00f9 di 1.500 anni fa), e i giorni della canicola non iniziano prima della fine di agosto in termini puramente astronomici. Sul calendario, invece, rimangono invariati.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e0c5bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e0c5bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-635c798\" data-id=\"635c798\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b21dac2 elementor-widget elementor-widget-image\" data-id=\"b21dac2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund-1024x683.jpg\" class=\"attachment-large size-large wp-image-27227\" alt=\"Sch\u00e4ferhund\" srcset=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund-1024x683.jpg 1024w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund-300x200.jpg 300w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund-768x512.jpg 768w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund-600x400.jpg 600w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Schaeferhund.jpg 1200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bbd7eb5\" data-id=\"bbd7eb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a710a9a elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"a710a9a\" data-element_type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tAi cani non piace il caldo e la calura estiva pu\u00f2 addirittura diventare un rischio per la loro salute. Date al vostro cane l'opportunit\u00e0 di rinfrescarsi.\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-df3c065 elementor-widget elementor-widget-spacer\" data-id=\"df3c065\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57a6285 elementor-widget elementor-widget-text-editor\" data-id=\"57a6285\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ecco come potete aiutare il vostro cane a rimanere fresco durante le giornate canicolari, anche quando il caldo \u00e8 eccessivo:<\/strong><\/p>\n<ul>\n<li>Tutte le attivit\u00e0 faticose all&#8217;aperto, come lunghe passeggiate o sessioni di addestramento, dovrebbero svolgersi nelle ore fresche del mattino o solo la sera. I cani corrono il rischio di subire un colpo di calore a causa dell&#8217;eccessivo esercizio fisico.<\/li>\n<li>Se il cane deve uscire comunque durante la parte calda della giornata, scegliete un percorso ombreggiato e lontano dall&#8217;asfalto. Infatti, l\u2019asfalto si riscalda molto e pu\u00f2 causare bruciature alle zampe (gi\u00e0 con una temperatura dell&#8217;aria di 25 \u00b0C, \u00e8 possibile che la temperatura dell&#8217;asfalto superi i 50 \u00b0C).<\/li>\n<li>Portatevi appresso dell&#8217;acqua fresca da bere non solo per voi, ma anche per il vostro cane.<\/li>\n<li>Concedetegli una siesta in un luogo ombreggiato.<\/li>\n<li>Se al vostro amico a quattro zampe piace nuotare, fategli fare una nuotata rinfrescante in una piscina per bambini, in un ruscello, in un fiume o in un lago. Attenzione: verificate la possibile presenza di alghe blu-verdi nell&#8217;acqua stagnante.<\/li>\n<li>In nessun caso il cane deve essere lasciato in auto, anche solo per poco tempo. Una volta riscaldata dal sole, l&#8217;auto si trasforma in pochi minuti in un forno rovente e pericoloso, anche se parcheggiata all&#8217;ombra per un breve periodo.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f902e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f902e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d71e552\" data-id=\"d71e552\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98ce526 elementor-widget elementor-widget-heading\" data-id=\"98ce526\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">World Dog Show 23. \u2013 27. Agosto 2023 a Ginevra<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-023f1c9 elementor-widget elementor-widget-text-editor\" data-id=\"023f1c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Oggi vogliamo ricordarvi l&#8217;imminente scadenza per l&#8217;iscrizione all&#8217;Esposizione Mondiale Canina di Ginevra, un evento che voi e il vostro amato amico a quattro zampe non dovreste perdere! L&#8217;Esposizione Mondiale Canina di quest&#8217;anno si terr\u00e0 dal 23 al 27 agosto 2023 nella splendida citt\u00e0 di Ginevra, proprio qui in Svizzera. L&#8217;evento si terr\u00e0 nei magnifici padiglioni di Palexpo, che offrono un ambiente ideale.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70b757f elementor-widget elementor-widget-text-editor\" data-id=\"70b757f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Cosa aspettarsi :<\/strong><\/p>\n<ul>\n<li>La settimana dell&#8217;Esposizione Mondiale Canina offre diverse mostre come il Grand Prix de Gen\u00e8ve, un&#8217;esposizione internazionale CACIB per tutte le razze e molti Raduni (Clubshow) organizzati dai club di razza, dove il vostro cane sar\u00e0 giudicato da giudici esperti.<\/li>\n<li>Variet\u00e0 di razze: Grandi o piccoli che siano, all&#8217;Esposizione Mondiale Canina troverete una grande variet\u00e0 di razze provenienti da tutto il mondo. \u00c8 un&#8217;ottima occasione per incontrare altri amanti dei cani e conoscere le caratteristiche delle diverse razze.<\/li>\n<li>Eventi e attivit\u00e0 emozionanti: Oltre alle competizioni, l&#8217;Esposizione Mondiale Canina offre una variet\u00e0 di eventi e attivit\u00e0 per visitatori di tutte le et\u00e0. Dalle dimostrazioni di Junior Handling per ragazzi agli stand informativi e di vendita di accessori per cani, ci sar\u00e0 molto da scoprire e da divertirsi.<\/li>\n<li>Anche i visitatori sono i benvenuti all&#8217;Esposizione Mondiale Canina. \u00c8 possibile acquistare facilmente i biglietti per visitatori all&#8217;ingresso il giorno dell&#8217;esposizione o gi\u00e0 online.<br><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5c4256 elementor-widget elementor-widget-text-editor\" data-id=\"b5c4256\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Titoli e omologazioni<\/strong><\/p>\n<p>All&#8217;Esposizione Mondiale Canina, come di consueto, verr\u00e0 assegnato un CAC in ogni classe. Per l&#8217;Esposizione Mondiale Canina \u00e8 previsto un regolamento speciale per il Campionato \u201cSwiss Show Champion\u201d, \u201cSwiss Junior Show Champion\u201d e \u201cSwiss Veteran Show Champion\u201d. Per ottenere il titolo, il cane deve ricevere i seguenti due CAC: un CAC dal Grand Prix CACIB Show (23.08.2023) o dal Raduno (Clubshow) e un CAC dal World Dog Show 2023 (24.08.-27.08.2023).<\/p>\n<p><em>*La regola dei due CAC si applica una sola volta per l&#8217;Esposizione Mondiale Canina 23-27.08.2023.<\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f697c34 elementor-widget elementor-widget-text-editor\" data-id=\"f697c34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Ultimo termine di iscrizione: 23 luglio 2023<\/strong><\/p>\n<p>La data di chiusura delle iscrizioni all&#8217;Esposizione Mondiale Canina si avvicina a grandi passi. Non dimenticate di iscrivere il vostro cane in tempo per assicurarvi la possibilit\u00e0 di partecipare a questo straordinario evento. <a href=\"https:\/\/www.onlinedogshows.eu\/en\/Show\/Index\/2549\/WorlddogShow2023_GrandprixdeGen_ve_Specialties#summary\" target=\"_blank\" rel=\"noopener\">Le iscrizioni si effettuano online su Online Dogshows, cliccate qui per accedere alla piattaforma di iscrizione.<\/a><\/p>\n<p>Per ulteriori informazioni sulla procedura di iscrizione, sui requisiti di iscrizione e sulla documentazione richiesta, visitate il sito web ufficiale dell&#8217;Esposizione Mondiale Canina all&#8217;indirizzo <a href=\"https:\/\/worlddogshow.ch\/en\/home\/\" target=\"_blank\" rel=\"noopener\">www.worlddogshow.ch<\/a>.<\/p>\n<p>Non vediamo l&#8217;ora di accogliere voi e i vostri fedeli compagni a Ginevra e di creare insieme un&#8217;esperienza indimenticabile. Riservate i vostri posti!<\/p>\n<p>&nbsp;<\/p>\n<p>Carissmi saluti,<br \/>\nIl team WDS Ginevra<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-593e7b7 elementor-widget elementor-widget-image\" data-id=\"593e7b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/worlddogshow.ch\/en\/home\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"600\" src=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023.jpg\" class=\"attachment-full size-full wp-image-15185\" alt=\"\" srcset=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023.jpg 1200w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023-300x150.jpg 300w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023-1024x512.jpg 1024w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023-768x384.jpg 768w, https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/02\/WORLD-DOG-SHOW-2023-600x300.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d752eea elementor-widget elementor-widget-spacer\" data-id=\"d752eea\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2deef53 elementor-widget elementor-widget-button\" data-id=\"2deef53\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Newsletter-Juli-2023-IT.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download come PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<div class=\"verein\"><\/div><p>Non sono solo le persone a soffrire il caldo in piena estate: anche i nostri amici a quattro zampe non lo sopportano. Se seguite alcuni semplici accorgimenti, aiuterete il vostro [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":27223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,89,74,58],"tags":[],"class_list":["post-27281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausstellungen","category-newsletter-it","category-newsletter","category-startseite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG\" \/>\n<meta property=\"og:description\" content=\"Non sono solo le persone a soffrire il caldo in piena estate: anche i nostri amici a quattro zampe non lo sopportano. Se seguite alcuni semplici accorgimenti, aiuterete il vostro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\" \/>\n<meta property=\"og:site_name\" content=\"SKG\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-19T09:24:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T10:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaktionhund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaktionhund\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\"},\"author\":{\"name\":\"redaktionhund\",\"@id\":\"https:\/\/www.skg.ch\/it\/#\/schema\/person\/a787ee9c3fd1b7bf58938293df9ada72\"},\"headline\":\"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco!\",\"datePublished\":\"2023-07-19T09:24:12+00:00\",\"dateModified\":\"2024-06-18T10:55:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\"},\"wordCount\":866,\"publisher\":{\"@id\":\"https:\/\/www.skg.ch\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg\",\"articleSection\":[\"Ausstellungen\",\"Newsletter\",\"Newsletter\",\"Startseite\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\",\"url\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\",\"name\":\"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG\",\"isPartOf\":{\"@id\":\"https:\/\/www.skg.ch\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg\",\"datePublished\":\"2023-07-19T09:24:12+00:00\",\"dateModified\":\"2024-06-18T10:55:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage\",\"url\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg\",\"contentUrl\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Hitze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.skg.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.skg.ch\/it\/#website\",\"url\":\"https:\/\/www.skg.ch\/it\/\",\"name\":\"SKG\",\"description\":\"Schweizerische Kynologische Gesellschaft\",\"publisher\":{\"@id\":\"https:\/\/www.skg.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.skg.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.skg.ch\/it\/#organization\",\"name\":\"SKG\",\"url\":\"https:\/\/www.skg.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.skg.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2022\/09\/Logo_Grau.png\",\"contentUrl\":\"https:\/\/www.skg.ch\/wp-content\/uploads\/2022\/09\/Logo_Grau.png\",\"width\":287,\"height\":64,\"caption\":\"SKG\"},\"image\":{\"@id\":\"https:\/\/www.skg.ch\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.skg.ch\/it\/#\/schema\/person\/a787ee9c3fd1b7bf58938293df9ada72\",\"name\":\"redaktionhund\",\"url\":\"https:\/\/www.skg.ch\/it\/author\/redaktionhund\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG","og_description":"Non sono solo le persone a soffrire il caldo in piena estate: anche i nostri amici a quattro zampe non lo sopportano. Se seguite alcuni semplici accorgimenti, aiuterete il vostro [&hellip;]","og_url":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/","og_site_name":"SKG","article_published_time":"2023-07-19T09:24:12+00:00","article_modified_time":"2024-06-18T10:55:03+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg","type":"image\/jpeg"}],"author":"redaktionhund","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redaktionhund","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#article","isPartOf":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/"},"author":{"name":"redaktionhund","@id":"https:\/\/www.skg.ch\/it\/#\/schema\/person\/a787ee9c3fd1b7bf58938293df9ada72"},"headline":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco!","datePublished":"2023-07-19T09:24:12+00:00","dateModified":"2024-06-18T10:55:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/"},"wordCount":866,"publisher":{"@id":"https:\/\/www.skg.ch\/it\/#organization"},"image":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg","articleSection":["Ausstellungen","Newsletter","Newsletter","Startseite"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/","url":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/","name":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco! - SKG","isPartOf":{"@id":"https:\/\/www.skg.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage"},"image":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg","datePublished":"2023-07-19T09:24:12+00:00","dateModified":"2024-06-18T10:55:03+00:00","breadcrumb":{"@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#primaryimage","url":"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg","contentUrl":"https:\/\/www.skg.ch\/wp-content\/uploads\/2023\/07\/Hitze-scaled.jpg","width":2560,"height":1707,"caption":"Hitze"},{"@type":"BreadcrumbList","@id":"https:\/\/www.skg.ch\/it\/a-qualcuno-non-piace-caldo-tenete-il-vostro-cane-al-fresco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.skg.ch\/it\/"},{"@type":"ListItem","position":2,"name":"\u201cA qualcuno non piace caldo\u201d: tenete il vostro cane al fresco!"}]},{"@type":"WebSite","@id":"https:\/\/www.skg.ch\/it\/#website","url":"https:\/\/www.skg.ch\/it\/","name":"SKG","description":"Schweizerische Kynologische Gesellschaft","publisher":{"@id":"https:\/\/www.skg.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.skg.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.skg.ch\/it\/#organization","name":"SKG","url":"https:\/\/www.skg.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.skg.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.skg.ch\/wp-content\/uploads\/2022\/09\/Logo_Grau.png","contentUrl":"https:\/\/www.skg.ch\/wp-content\/uploads\/2022\/09\/Logo_Grau.png","width":287,"height":64,"caption":"SKG"},"image":{"@id":"https:\/\/www.skg.ch\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.skg.ch\/it\/#\/schema\/person\/a787ee9c3fd1b7bf58938293df9ada72","name":"redaktionhund","url":"https:\/\/www.skg.ch\/it\/author\/redaktionhund\/"}]}},"_links":{"self":[{"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/posts\/27281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/comments?post=27281"}],"version-history":[{"count":9,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/posts\/27281\/revisions"}],"predecessor-version":[{"id":35827,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/posts\/27281\/revisions\/35827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/media\/27223"}],"wp:attachment":[{"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/media?parent=27281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/categories?post=27281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.skg.ch\/it\/wp-json\/wp\/v2\/tags?post=27281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}